{"id":5687,"date":"2015-03-16T17:50:06","date_gmt":"2015-03-16T16:50:06","guid":{"rendered":"https:\/\/reuniwatt.com\/fr\/?p=5687"},"modified":"2020-08-19T14:33:09","modified_gmt":"2020-08-19T13:33:09","slug":"decouplage-entre-leconomie-et-les-emissions-carbone","status":"publish","type":"post","link":"https:\/\/reuniwatt.com\/fr\/actu-industrie\/decouplage-entre-leconomie-et-les-emissions-carbone\/","title":{"rendered":"D\u00e9couplage entre l\u2019\u00e9conomie et les \u00e9missions carbone ?"},"content":{"rendered":"<p style=\"text-align: justify\">Bonne nouvelle ! <strong><a href=\"mailto:http:\/\/www.iea.org\/newsroomandevents\/news\/2015\/march\/global-energy-related-emissions-of-carbon-dioxide-stalled-in-2014.html\">L\u2019Agence Internationale de l\u2019Energie (IEA) vient de d\u00e9voiler une \u00e9tude<\/a><\/strong> affirmant que les \u00e9missions de dioxyde de carbone (CO<sub>2<\/sub>) li\u00e9es \u00e0 l\u2019\u00e9nergie n\u2019ont pas augment\u00e9 en 2014.<\/p>\n<p>Habituellement, on peut observer une forte corr\u00e9lation entre la sant\u00e9 de l\u2019\u00e9conomie mondiale et la quantit\u00e9 de dioxyde de carbone \u00e9mise dans l\u2019atmosph\u00e8re\u00a0: plus l\u2019\u00e9conomie cro\u00eet, plus l\u2019\u00e9nergie est utilis\u00e9e pour alimenter cette croissance. Cela est surtout vrai lorsque cette-derni\u00e8re provient de pays \u00e9mergeants o\u00f9 de plus en plus d\u2019individus ont acc\u00e8s \u00e0 diff\u00e9rentes sources d\u2019\u00e9nergie (\u00e9lectricit\u00e9, fuel, etc..). Par le pass\u00e9, lorsque l\u2019\u00e9conomie a ralenti, on a m\u00eame identifi\u00e9 une baisse dans les \u00e9missions (cela est d\u00e9j\u00e0 arriv\u00e9 trois fois\u00a0: au d\u00e9but des ann\u00e9es 80, en 1992 et en 2009).<\/p>\n<p style=\"text-align: justify\">Pourtant, en 2014, l\u2019\u00e9conomie mondiale a cr\u00fb de 3%. Cela signifie que l\u2019ann\u00e9e derni\u00e8re, les \u00e9missions de CO<sub>2<\/sub> et l\u2019\u00e9conomie \u00e9taient moins corr\u00e9l\u00e9es, principalement gr\u00e2ce aux m\u00e9thodes d\u2019\u00e9conomie d\u2019\u00e9nergie et aux sources d\u2019\u00e9nergie propres telles que l\u2019\u00e9nergie solaire\u00a0!<br \/>\nCela veut-il dire que le r\u00e9chauffement climatique n\u2019aura pas lieu et que nous allons r\u00e9ussir \u00e0 maintenir la hausse des temp\u00e9ratures en dessous de 2\u00b0C par rapport \u00e0 la temp\u00e9rature moyenne de l\u2019\u00e8re pr\u00e9industrielle\u00a0?<br \/>\nPas vraiment. M\u00eame si ce r\u00e9sultat montre que nous sommes sur la bonne voie en ce qui concerne la baisse des \u00e9missions de CO<sub>2<\/sub> et que les actions prises ont un effet tangible, il ne faut pas rel\u00e2cher l\u2019effort. Quelques explications\u00a0:<\/p>\n<ol style=\"text-align: justify\">\n<li>L\u2019IEA n\u2019a pas mesur\u00e9 les \u00e9missions de CO<sub>2<\/sub> directement \u00e0 toutes les sources. L\u2019agence a appliqu\u00e9 un mod\u00e8le statistique liant la production et la consommation d\u2019\u00e9nergie \u00e0 leurs \u00e9missions respectives en fonction des modes de production et des activit\u00e9s consommatrices. Cependant, la barre d\u2019erreur sur de telles estimations est s\u00fbrement significative, et certaines activit\u00e9s consommatrices d\u2019\u00e9nergie n\u2019ont peut-\u00eatre pas \u00e9t\u00e9 prises en compte.<br \/>\nAu final, l\u2019incertitude sur le r\u00e9sultat est probablement non n\u00e9gligeable et les \u00e9missions de CO<sub>2<\/sub> ne sont peut-\u00eatre pas celles annonc\u00e9es par l\u2019IEA. Il faudrait que cette \u00e9tude soit poursuivie sur le long terme pour voir si une tendance apparait effectivement et s\u2019il est possible de la relier quantitativement aux m\u00e9thodes d\u2019effacement et de production d\u2019\u00e9nergie propre.<\/li>\n<li>La production et la consommation d\u2019\u00e9nergie ne sont pas les seules responsables des \u00e9missions de CO<sub>2<\/sub>. M\u00eame s\u2019il s\u2019agit de la principale cause, l\u2019agriculture et la d\u00e9forestation en sont \u00e9galement responsables, et des efforts devraient \u00e9galement \u00eatre poursuivis dans ces domaines.<\/li>\n<li>Le CO<sub>2<\/sub> n\u2019est pas le seul gaz \u00e0 effet de serre. Par exemple, le m\u00e9thane (CH<sub>4<\/sub>) a un effet vingt fois sup\u00e9rieur au CO<sub>2<\/sub>. Il faut aussi r\u00e9fl\u00e9chir \u00e0 rem\u00e9dier \u00e0 ces \u00e9missions, m\u00eames si elles sont moins m\u00e9diatis\u00e9es.<\/li>\n<li>Un arr\u00eat de l\u2019augmentation des \u00e9missions ne veut pas dire plus d\u2019\u00e9mission du tout. M\u00eame si les niveaux d\u2019\u00e9missions restent les m\u00eames, cela signifie que l\u2019on injecte toujours d\u2019\u00e9normes quantit\u00e9s de dioxyde de carbone dans l\u2019atmosph\u00e8re. Pour preuve\u00a0: ci-dessous le graphique de l\u2019Agence Am\u00e9ricaine pour les Oc\u00e9ans et l\u2019Atmosph\u00e8re (NOAA) sur l\u2019\u00e9volution de la concentration en CO<sub>2<\/sub> \u00e0 l\u2019<strong><a href=\"mailto:http:\/\/www.esrl.noaa.gov\/gmd\/obop\/mlo\/\">Observatoire de Mauna Loa, \u00e0 Hawaii<\/a><\/strong>\u00a0:<\/li>\n<\/ol>\n<p><a href=\"https:\/\/reuniwatt.com\/fr\/wp-content\/uploads\/sites\/2\/2015\/03\/NOAA.png\"><img decoding=\"async\" class=\" wp-image-5688 aligncenter\" src=\"https:\/\/reuniwatt.com\/fr\/wp-content\/uploads\/sites\/2\/2015\/03\/NOAA.png\" alt=\"NOAA\" width=\"654\" height=\"478\" srcset=\"https:\/\/reuniwatt.com\/fr\/wp-content\/uploads\/sites\/2\/2015\/03\/NOAA-220x161.png 220w, https:\/\/reuniwatt.com\/fr\/wp-content\/uploads\/sites\/2\/2015\/03\/NOAA-300x219.png 300w, https:\/\/reuniwatt.com\/fr\/wp-content\/uploads\/sites\/2\/2015\/03\/NOAA.png 792w\" sizes=\"(max-width: 654px) 100vw, 654px\" \/><\/a><\/p>\n<p style=\"text-align: justify\">Conclusion\u00a0: ceci est un r\u00e9sultat pr\u00e9liminaire encourageant, mais nous devons continuer \u00e0 installer de nouvelles sources d\u2019\u00e9nergie renouvelables afin de s\u2019attaquer au r\u00e9chauffement climatique et inverser la tendance. L\u2019\u00e9nergie solaire est la solution\u00a0!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bonne nouvelle ! L\u2019Agence Internationale de l\u2019Energie (IEA) vient de d\u00e9voiler une \u00e9tude affirmant que les \u00e9missions de dioxyde de carbone (CO2) li\u00e9es \u00e0 l\u2019\u00e9nergie n\u2019ont pas augment\u00e9 en 2014. Habituellement, on peut observer une forte corr\u00e9lation entre la sant\u00e9 de l\u2019\u00e9conomie mondiale et la quantit\u00e9 de dioxyde de carbone \u00e9mise dans l\u2019atmosph\u00e8re\u00a0: plus l\u2019\u00e9conomie cro\u00eet, plus l\u2019\u00e9nergie est utilis\u00e9e pour alimenter cette croissance. Cela<\/p>\n","protected":false},"author":3,"featured_media":5689,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[32],"tags":[107,108,109],"class_list":["post-5687","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actu-industrie","tag-agence-international-de-lenergie","tag-co2","tag-emissions-de-gaz-a-effet-de-serre"],"_links":{"self":[{"href":"https:\/\/reuniwatt.com\/fr\/wp-json\/wp\/v2\/posts\/5687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reuniwatt.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reuniwatt.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reuniwatt.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/reuniwatt.com\/fr\/wp-json\/wp\/v2\/comments?post=5687"}],"version-history":[{"count":4,"href":"https:\/\/reuniwatt.com\/fr\/wp-json\/wp\/v2\/posts\/5687\/revisions"}],"predecessor-version":[{"id":11689,"href":"https:\/\/reuniwatt.com\/fr\/wp-json\/wp\/v2\/posts\/5687\/revisions\/11689"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/reuniwatt.com\/fr\/wp-json\/wp\/v2\/media\/5689"}],"wp:attachment":[{"href":"https:\/\/reuniwatt.com\/fr\/wp-json\/wp\/v2\/media?parent=5687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reuniwatt.com\/fr\/wp-json\/wp\/v2\/categories?post=5687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reuniwatt.com\/fr\/wp-json\/wp\/v2\/tags?post=5687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}